{"id":546,"date":"2022-12-13T16:59:12","date_gmt":"2022-12-13T16:59:12","guid":{"rendered":"https:\/\/www.clinicadecancerologiadelnortedesantander.com\/?page_id=546"},"modified":"2026-03-10T16:08:44","modified_gmt":"2026-03-10T16:08:44","slug":"pqrs-2022-01","status":"publish","type":"page","link":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/","title":{"rendered":"PQRS 2022-01"},"content":{"rendered":"<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/clinicadecancerologians.com\/wp-content\/uploads\/2022\/12\/pqrs-2022-01.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">pqrs-2022-01<\/a><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":221,"parent":485,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-546","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PQRS 2022-01 - Clinica de Cancerologia del Norte de Santander<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PQRS 2022-01 - Clinica de Cancerologia del Norte de Santander\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Clinica de Cancerologia del Norte de Santander\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100068487632832\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T16:08:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicadecancerologians.com\/wp-content\/uploads\/2019\/04\/IMG_1220.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/pqrs-2022-01\\\/\",\"url\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/pqrs-2022-01\\\/\",\"name\":\"PQRS 2022-01 - Clinica de Cancerologia del Norte de Santander\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/pqrs-2022-01\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/pqrs-2022-01\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadecancerologians.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/IMG_1220.jpg\",\"datePublished\":\"2022-12-13T16:59:12+00:00\",\"dateModified\":\"2026-03-10T16:08:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/pqrs-2022-01\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/pqrs-2022-01\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/pqrs-2022-01\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicadecancerologians.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/IMG_1220.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadecancerologians.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/IMG_1220.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/pqrs-2022-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadecancerologians.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nosotros\",\"item\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gesti\u00f3n PQRS\",\"item\":\"https:\\\/\\\/clinicadecancerologians.com\\\/index.php\\\/nosotros\\\/estadistica-pqrs\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"PQRS 2022-01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/#website\",\"url\":\"https:\\\/\\\/clinicadecancerologians.com\\\/\",\"name\":\"Clinica de Cancerologia del Norte de Santander\",\"description\":\"En Busca De una Mejor Calidad de Vida\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadecancerologians.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/#organization\",\"name\":\"Clinica de Cancerologia del Norte de Santander\",\"url\":\"https:\\\/\\\/clinicadecancerologians.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadecancerologians.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CANCEROLOGIA2.png\",\"contentUrl\":\"https:\\\/\\\/clinicadecancerologians.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CANCEROLOGIA2.png\",\"width\":394,\"height\":215,\"caption\":\"Clinica de Cancerologia del Norte de Santander\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadecancerologians.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100068487632832\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PQRS 2022-01 - Clinica de Cancerologia del Norte de Santander","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/","og_locale":"es_ES","og_type":"article","og_title":"PQRS 2022-01 - Clinica de Cancerologia del Norte de Santander","og_url":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/","og_site_name":"Clinica de Cancerologia del Norte de Santander","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100068487632832","article_modified_time":"2026-03-10T16:08:44+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/clinicadecancerologians.com\/wp-content\/uploads\/2019\/04\/IMG_1220.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/","url":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/","name":"PQRS 2022-01 - Clinica de Cancerologia del Norte de Santander","isPartOf":{"@id":"https:\/\/clinicadecancerologians.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/#primaryimage"},"image":{"@id":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadecancerologians.com\/wp-content\/uploads\/2019\/04\/IMG_1220.jpg","datePublished":"2022-12-13T16:59:12+00:00","dateModified":"2026-03-10T16:08:44+00:00","breadcrumb":{"@id":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/#primaryimage","url":"https:\/\/clinicadecancerologians.com\/wp-content\/uploads\/2019\/04\/IMG_1220.jpg","contentUrl":"https:\/\/clinicadecancerologians.com\/wp-content\/uploads\/2019\/04\/IMG_1220.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/pqrs-2022-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadecancerologians.com\/"},{"@type":"ListItem","position":2,"name":"Nosotros","item":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/"},{"@type":"ListItem","position":3,"name":"Gesti\u00f3n PQRS","item":"https:\/\/clinicadecancerologians.com\/index.php\/nosotros\/estadistica-pqrs\/"},{"@type":"ListItem","position":4,"name":"PQRS 2022-01"}]},{"@type":"WebSite","@id":"https:\/\/clinicadecancerologians.com\/#website","url":"https:\/\/clinicadecancerologians.com\/","name":"Clinica de Cancerologia del Norte de Santander","description":"En Busca De una Mejor Calidad de Vida","publisher":{"@id":"https:\/\/clinicadecancerologians.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadecancerologians.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clinicadecancerologians.com\/#organization","name":"Clinica de Cancerologia del Norte de Santander","url":"https:\/\/clinicadecancerologians.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clinicadecancerologians.com\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadecancerologians.com\/wp-content\/uploads\/2019\/04\/CANCEROLOGIA2.png","contentUrl":"https:\/\/clinicadecancerologians.com\/wp-content\/uploads\/2019\/04\/CANCEROLOGIA2.png","width":394,"height":215,"caption":"Clinica de Cancerologia del Norte de Santander"},"image":{"@id":"https:\/\/clinicadecancerologians.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100068487632832"]}]}},"_links":{"self":[{"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/pages\/546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/comments?post=546"}],"version-history":[{"count":2,"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/pages\/546\/revisions"}],"predecessor-version":[{"id":1044,"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/pages\/546\/revisions\/1044"}],"up":[{"embeddable":true,"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/pages\/485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/media\/221"}],"wp:attachment":[{"href":"https:\/\/clinicadecancerologians.com\/index.php\/wp-json\/wp\/v2\/media?parent=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}